{"id":13829,"date":"2024-03-16T14:12:39","date_gmt":"2024-03-16T13:12:39","guid":{"rendered":"https:\/\/gauthiercerf.com\/ausstellung\/galerie-am-lindenhof-2024\/"},"modified":"2024-07-07T13:56:50","modified_gmt":"2024-07-07T11:56:50","slug":"galerie-am-lindenhof-2024","status":"publish","type":"ausstellung_post","link":"https:\/\/gauthiercerf.com\/en\/ausstellung\/galerie-am-lindenhof-2024\/","title":{"rendered":"Galerie am Lindenhof 2024"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"13829\" class=\"elementor elementor-13829 elementor-13562\" data-elementor-settings=\"{&quot;ha_cmc_init_switcher&quot;:&quot;no&quot;}\" data-elementor-post-type=\"ausstellung_post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-55cb33e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"55cb33e\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2736f7f\" data-id=\"2736f7f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4685d26 elementor-widget elementor-widget-heading\" data-id=\"4685d26\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Galerie am Lindenhof<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a4602d8 elementor-widget elementor-widget-text-editor\" data-id=\"a4602d8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Art enthusiast Sonja Lacher has been running the <a style=\"background-color: #ffffff;\" href=\"https:\/\/www.galerieamlindenhof.ch\/\" target=\"_blank\" rel=\"noopener\">Galerie am Lindenhof<\/a> art space since 2019. She herself is an artist and photographer.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9cfdf2f elementor-widget elementor-widget-text-editor\" data-id=\"9cfdf2f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>The Galerie am Lindenhof is located in the heart of Zurich between the Lindenhof viewpoint and Rennweg.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1f2ffe4 elementor-widget elementor-widget-google_maps\" data-id=\"1f2ffe4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"google_maps.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-custom-embed\">\n\t\t\t<iframe loading=\"lazy\"\n\t\t\t\t\tsrc=\"https:\/\/maps.google.com\/maps?q=Pfalzgasse%203%2C%208001%20Z%C3%BCrich%2C%20Schweiz&#038;t=m&#038;z=14&#038;output=embed&#038;iwloc=near\"\n\t\t\t\t\ttitle=\"Pfalzgasse 3, 8001 Z\u00fcrich, Schweiz\"\n\t\t\t\t\taria-label=\"Pfalzgasse 3, 8001 Z\u00fcrich, Schweiz\"\n\t\t\t><\/iframe>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-f40864e\" data-id=\"f40864e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-97e874f elementor-widget elementor-widget-heading\" data-id=\"97e874f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Opening hours<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9771ade elementor-widget elementor-widget-text-editor\" data-id=\"9771ade\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>June 18 &#8211; 24, 2024<\/p>\n<p>Tue 18.06. 4 &#8211; 7 pm<br \/>\nWed &#8211; Sun 19 &#8211; 23.06. 1 &#8211; 7 pm<br \/>\nMon 24.06. Noon &#8211; 4 pm<\/p>\n<p>The <strong>vernissage<\/strong> will take place on <strong>June 19, 2024 from 6 pm<\/strong> in the gallery and is open to everyone. Registration via email is requested.<\/p>\n<p>On <strong>Sun 23.06.2024 at 3 &#8211; 4 pm<\/strong> there will be an <strong>artist talk about Fibonacci<\/strong> and its background in the artworks.<\/p>\n<p>For guided tours at other times, you can contact me via email (<a href=\"&#109;&#x61;&#105;&#x6c;&#116;&#x6f;&#58;&#x67;&#97;&#x75;&#116;&#x68;&#101;&#x72;&#64;&#x67;&#97;&#x75;&#116;&#x68;&#105;&#x65;&#114;&#x63;&#101;&#x72;f&#x2e;c&#x6f;m\" target=\"_blank\" rel=\"noopener\">&#x67;&#x61;&#117;&#116;hi&#x65;&#x72;&#x40;&#103;au&#x74;&#x68;&#x69;&#101;&#114;c&#x65;&#x72;&#x66;&#46;&#99;o&#x6d;<\/a>).<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bdfea57 elementor-widget elementor-widget-heading\" data-id=\"bdfea57\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Exhibited Works<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f7eb47b elementor-widget elementor-widget-text-editor\" data-id=\"f7eb47b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tThe <a href=\"https:\/\/gauthiercerf.com\/en\/artwork\/fibonacci-matryoshka\/\" target=\"_blank\" rel=\"noopener\">Fibonacci Matryoshka<\/a> sculpture and the <a href=\"https:\/\/gauthiercerf.com\/en\/artwork\/fibonacci-ladder-iv-stele\/\" target=\"_blank\" rel=\"noopener\">Fibonacci Ladder in the form of a stele<\/a> will be shown for the first time at the exhibition.\r\n\r\nA selection of new paintings from the Fibonacci Ladder and Curved Kite series will also be on display, as well as the works <span style=\"color: var( --e-global-color-text );\">\u00a0<\/span><a href=\"https:\/\/gauthiercerf.com\/en\/artwork\/fibonacci-finds-mondrian\/\" target=\"_blank\" rel=\"noopener\">Fibonacci Finds Mondrian<\/a><span style=\"color: var( --e-global-color-text );\"> and\u00a0<\/span><a href=\"https:\/\/gauthiercerf.com\/en\/artwork\/fibonacci-twin-galaxies\/\" target=\"_blank\" rel=\"noopener\">Fibonacci Twin Galaxies<\/a>.\r\n\r\nCome along and be surprised.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Galerie am Lindenhof Art enthusiast Sonja Lacher has been running the Galerie am Lindenhof art space since 2019. She herself is an artist and photographer. The Galerie am Lindenhof is located in the heart of Zurich between the Lindenhof viewpoint and Rennweg. Opening hours June 18 &#8211; 24, 2024 Tue 18.06. 4 &#8211; 7 pm [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":14983,"menu_order":0,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"ausstellung_category":[74],"class_list":["post-13829","ausstellung_post","type-ausstellung_post","status-publish","format-standard","has-post-thumbnail","hentry","ausstellung_category-vergangene-en"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Galerie am Lindenhof 2024 - Gauthier Cerf Art<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gauthiercerf.com\/en\/ausstellung\/galerie-am-lindenhof-2024\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Galerie am Lindenhof 2024 - Gauthier Cerf Art\" \/>\n<meta property=\"og:description\" content=\"Galerie am Lindenhof Art enthusiast Sonja Lacher has been running the Galerie am Lindenhof art space since 2019. She herself is an artist and photographer. The Galerie am Lindenhof is located in the heart of Zurich between the Lindenhof viewpoint and Rennweg. Opening hours June 18 &#8211; 24, 2024 Tue 18.06. 4 &#8211; 7 pm [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gauthiercerf.com\/en\/ausstellung\/galerie-am-lindenhof-2024\/\" \/>\n<meta property=\"og:site_name\" content=\"Gauthier Cerf Art\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-07T11:56:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/gauthiercerf.com\/wp-content\/uploads\/2024\/06\/GFA_Flyer_Lindenhof_FINAL_Vorderseite.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1749\" \/>\n\t<meta property=\"og:image:height\" content=\"2481\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/gauthiercerf.com\\\/en\\\/ausstellung\\\/galerie-am-lindenhof-2024\\\/\",\"url\":\"https:\\\/\\\/gauthiercerf.com\\\/en\\\/ausstellung\\\/galerie-am-lindenhof-2024\\\/\",\"name\":\"Galerie am Lindenhof 2024 - Gauthier Cerf Art\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gauthiercerf.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/gauthiercerf.com\\\/en\\\/ausstellung\\\/galerie-am-lindenhof-2024\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/gauthiercerf.com\\\/en\\\/ausstellung\\\/galerie-am-lindenhof-2024\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gauthiercerf.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/GFA_Flyer_Lindenhof_FINAL_Vorderseite.jpg\",\"datePublished\":\"2024-03-16T13:12:39+00:00\",\"dateModified\":\"2024-07-07T11:56:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/gauthiercerf.com\\\/en\\\/ausstellung\\\/galerie-am-lindenhof-2024\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/gauthiercerf.com\\\/en\\\/ausstellung\\\/galerie-am-lindenhof-2024\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/gauthiercerf.com\\\/en\\\/ausstellung\\\/galerie-am-lindenhof-2024\\\/#primaryimage\",\"url\":\"https:\\\/\\\/gauthiercerf.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/GFA_Flyer_Lindenhof_FINAL_Vorderseite.jpg\",\"contentUrl\":\"https:\\\/\\\/gauthiercerf.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/GFA_Flyer_Lindenhof_FINAL_Vorderseite.jpg\",\"width\":1749,\"height\":2481},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/gauthiercerf.com\\\/en\\\/ausstellung\\\/galerie-am-lindenhof-2024\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/gauthiercerf.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Galerie am Lindenhof 2024\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gauthiercerf.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/gauthiercerf.com\\\/en\\\/\",\"name\":\"Gauthier Cerf Art\",\"description\":\"Fibonacci Art\",\"publisher\":{\"@id\":\"https:\\\/\\\/gauthiercerf.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/gauthiercerf.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/gauthiercerf.com\\\/en\\\/#organization\",\"name\":\"Gauthier Cerf Art\",\"url\":\"https:\\\/\\\/gauthiercerf.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/gauthiercerf.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/gauthiercerf.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/Bildschirm\u00adfoto-2022-11-09-um-16.05.38.png\",\"contentUrl\":\"https:\\\/\\\/gauthiercerf.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/Bildschirm\u00adfoto-2022-11-09-um-16.05.38.png\",\"width\":218,\"height\":92,\"caption\":\"Gauthier Cerf Art\"},\"image\":{\"@id\":\"https:\\\/\\\/gauthiercerf.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Galerie am Lindenhof 2024 - Gauthier Cerf Art","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gauthiercerf.com\/en\/ausstellung\/galerie-am-lindenhof-2024\/","og_locale":"en_US","og_type":"article","og_title":"Galerie am Lindenhof 2024 - Gauthier Cerf Art","og_description":"Galerie am Lindenhof Art enthusiast Sonja Lacher has been running the Galerie am Lindenhof art space since 2019. She herself is an artist and photographer. The Galerie am Lindenhof is located in the heart of Zurich between the Lindenhof viewpoint and Rennweg. Opening hours June 18 &#8211; 24, 2024 Tue 18.06. 4 &#8211; 7 pm [&hellip;]","og_url":"https:\/\/gauthiercerf.com\/en\/ausstellung\/galerie-am-lindenhof-2024\/","og_site_name":"Gauthier Cerf Art","article_modified_time":"2024-07-07T11:56:50+00:00","og_image":[{"width":1749,"height":2481,"url":"https:\/\/gauthiercerf.com\/wp-content\/uploads\/2024\/06\/GFA_Flyer_Lindenhof_FINAL_Vorderseite.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/gauthiercerf.com\/en\/ausstellung\/galerie-am-lindenhof-2024\/","url":"https:\/\/gauthiercerf.com\/en\/ausstellung\/galerie-am-lindenhof-2024\/","name":"Galerie am Lindenhof 2024 - Gauthier Cerf Art","isPartOf":{"@id":"https:\/\/gauthiercerf.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/gauthiercerf.com\/en\/ausstellung\/galerie-am-lindenhof-2024\/#primaryimage"},"image":{"@id":"https:\/\/gauthiercerf.com\/en\/ausstellung\/galerie-am-lindenhof-2024\/#primaryimage"},"thumbnailUrl":"https:\/\/gauthiercerf.com\/wp-content\/uploads\/2024\/06\/GFA_Flyer_Lindenhof_FINAL_Vorderseite.jpg","datePublished":"2024-03-16T13:12:39+00:00","dateModified":"2024-07-07T11:56:50+00:00","breadcrumb":{"@id":"https:\/\/gauthiercerf.com\/en\/ausstellung\/galerie-am-lindenhof-2024\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gauthiercerf.com\/en\/ausstellung\/galerie-am-lindenhof-2024\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/gauthiercerf.com\/en\/ausstellung\/galerie-am-lindenhof-2024\/#primaryimage","url":"https:\/\/gauthiercerf.com\/wp-content\/uploads\/2024\/06\/GFA_Flyer_Lindenhof_FINAL_Vorderseite.jpg","contentUrl":"https:\/\/gauthiercerf.com\/wp-content\/uploads\/2024\/06\/GFA_Flyer_Lindenhof_FINAL_Vorderseite.jpg","width":1749,"height":2481},{"@type":"BreadcrumbList","@id":"https:\/\/gauthiercerf.com\/en\/ausstellung\/galerie-am-lindenhof-2024\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/gauthiercerf.com\/en\/"},{"@type":"ListItem","position":2,"name":"Galerie am Lindenhof 2024"}]},{"@type":"WebSite","@id":"https:\/\/gauthiercerf.com\/en\/#website","url":"https:\/\/gauthiercerf.com\/en\/","name":"Gauthier Cerf Art","description":"Fibonacci Art","publisher":{"@id":"https:\/\/gauthiercerf.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gauthiercerf.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/gauthiercerf.com\/en\/#organization","name":"Gauthier Cerf Art","url":"https:\/\/gauthiercerf.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/gauthiercerf.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/gauthiercerf.com\/wp-content\/uploads\/2022\/11\/Bildschirm\u00adfoto-2022-11-09-um-16.05.38.png","contentUrl":"https:\/\/gauthiercerf.com\/wp-content\/uploads\/2022\/11\/Bildschirm\u00adfoto-2022-11-09-um-16.05.38.png","width":218,"height":92,"caption":"Gauthier Cerf Art"},"image":{"@id":"https:\/\/gauthiercerf.com\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/gauthiercerf.com\/en\/wp-json\/wp\/v2\/ausstellung_post\/13829","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gauthiercerf.com\/en\/wp-json\/wp\/v2\/ausstellung_post"}],"about":[{"href":"https:\/\/gauthiercerf.com\/en\/wp-json\/wp\/v2\/types\/ausstellung_post"}],"author":[{"embeddable":true,"href":"https:\/\/gauthiercerf.com\/en\/wp-json\/wp\/v2\/users\/7"}],"version-history":[{"count":10,"href":"https:\/\/gauthiercerf.com\/en\/wp-json\/wp\/v2\/ausstellung_post\/13829\/revisions"}],"predecessor-version":[{"id":15007,"href":"https:\/\/gauthiercerf.com\/en\/wp-json\/wp\/v2\/ausstellung_post\/13829\/revisions\/15007"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gauthiercerf.com\/en\/wp-json\/wp\/v2\/media\/14983"}],"wp:attachment":[{"href":"https:\/\/gauthiercerf.com\/en\/wp-json\/wp\/v2\/media?parent=13829"}],"wp:term":[{"taxonomy":"ausstellung_category","embeddable":true,"href":"https:\/\/gauthiercerf.com\/en\/wp-json\/wp\/v2\/ausstellung_category?post=13829"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}